{"id":456356,"date":"2024-08-27T11:51:42","date_gmt":"2024-08-27T11:51:42","guid":{"rendered":"https:\/\/www.futllermo.com\/es\/?p=456356"},"modified":"2024-08-27T11:51:42","modified_gmt":"2024-08-27T11:51:42","slug":"plantilla-olympique-marsella","status":"publish","type":"post","link":"https:\/\/futllermo.com\/es\/plantilla-olympique-marsella\/","title":{"rendered":"Plantilla del Olympique de Marsella"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_81 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/futllermo.com\/es\/plantilla-olympique-marsella\/#Historia\" >Historia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/futllermo.com\/es\/plantilla-olympique-marsella\/#Figuras_emblematicas\" >Figuras emblem\u00e1ticas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/futllermo.com\/es\/plantilla-olympique-marsella\/#Estadio_y_aficion\" >Estadio y afici\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/futllermo.com\/es\/plantilla-olympique-marsella\/#Actualidad\" >Actualidad<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Historia\"><\/span>Historia<span class=\"ez-toc-section-end\"><\/span><\/h2><p>La plantilla del Olympique de Marsella es un equipo de f\u00fatbol franc\u00e9s fundado en 1899. Es uno de los clubes m\u00e1s exitosos de Francia, con 9 t\u00edtulos de la Ligue 1, 10 Copas de Francia y 3 Copas de la Liga. Tambi\u00e9n es un equipo muy reconocido en Europa, habiendo ganado la Liga de Campeones de la UEFA en 1993 y la Copa Intertoto de la UEFA en 2005.<\/p><p>Sin embargo, en 1994 el club se vio involucrado en un esc\u00e1ndalo de manipulaci\u00f3n de partidos, conocido como \u00abel affaire VA-OM\u00bb, que finalmente result\u00f3 en la exclusi\u00f3n del club de la liga y el descenso a segunda divisi\u00f3n. Aunque el club logr\u00f3 regresar a primera divisi\u00f3n en 1996 y continu\u00f3 cosechando \u00e9xitos, este episodio manch\u00f3 la historia del Olympique de Marsella.<\/p><h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Figuras_emblematicas\"><\/span>Figuras emblem\u00e1ticas<span class=\"ez-toc-section-end\"><\/span><\/h2><p>La plantilla del Olympique de Marsella ha contado con grandes figuras a lo largo de su historia. Entre ellos destacan jugadores como el mencionado Jean-Pierre Papin, quien fue uno de los mejores delanteros de Francia en la d\u00e9cada de 1990 y gan\u00f3 el Bal\u00f3n de Oro en 1991. Tambi\u00e9n jugadores como Franck Rib\u00e9ry, Didier Drogba, Samir Nasri y Dimitri Payet han dejado su huella en el club.<\/p><h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Estadio_y_aficion\"><\/span>Estadio y afici\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2><p>El Olympique de Marsella juega sus partidos como local en el Estadio V\u00e9lodrome, un ic\u00f3nico estadio con capacidad para m\u00e1s de 67.000 espectadores. Inaugurado en 1937, el V\u00e9lodrome ha sido testigo de grandes momentos del club y tambi\u00e9n ha sido sede de importantes eventos deportivos, como la final de la Copa del Mundo de 1998 y la final de la Liga de Campeones de la UEFA en 2000.<\/p><h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Actualidad\"><\/span>Actualidad<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Actualmente, la plantilla del Olympique de Marsella est\u00e1 dirigida por el entrenador argentino Jorge Sampaoli y cuenta con jugadores de gran talento como Florian Thauvin, Dimitri Payet y Dario Benedetto. En la temporada 2020-2021, el equipo logr\u00f3 calificar a la Liga de Campeones de la UEFA despu\u00e9s de un segundo lugar en la Ligue 1.<\/p>","protected":false},"excerpt":{"rendered":"<p>Historia La plantilla del Olympique de Marsella es un equipo de f\u00fatbol franc\u00e9s fundado en 1899. Es uno&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_joinchat":[],"footnotes":""},"categories":[27],"tags":[],"class_list":["post-456356","post","type-post","status-publish","format-standard","hentry","category-futbol"],"_links":{"self":[{"href":"https:\/\/futllermo.com\/es\/wp-json\/wp\/v2\/posts\/456356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futllermo.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/futllermo.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/futllermo.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/futllermo.com\/es\/wp-json\/wp\/v2\/comments?post=456356"}],"version-history":[{"count":0,"href":"https:\/\/futllermo.com\/es\/wp-json\/wp\/v2\/posts\/456356\/revisions"}],"wp:attachment":[{"href":"https:\/\/futllermo.com\/es\/wp-json\/wp\/v2\/media?parent=456356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/futllermo.com\/es\/wp-json\/wp\/v2\/categories?post=456356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/futllermo.com\/es\/wp-json\/wp\/v2\/tags?post=456356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}